{"id":644,"date":"2020-08-14T10:58:26","date_gmt":"2020-08-14T10:58:26","guid":{"rendered":"https:\/\/hgtrail-idrija.si\/?p=644"},"modified":"2020-08-17T10:07:44","modified_gmt":"2020-08-17T10:07:44","slug":"organizacija-okrepcevalnic","status":"publish","type":"post","link":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/","title":{"rendered":"Organizacija okrep\u010devalnic"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"644\" class=\"elementor elementor-644\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-218b339a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"218b339a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3085ad81\" data-id=\"3085ad81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d5b49d1 elementor-widget elementor-widget-text-editor\" data-id=\"3d5b49d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p class=\"wp-block-paragraph\">Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna. Zaradi dolo\u010dil in priporo\u010dil <b>NIJZ<\/b>, bo izbor na okrep\u010devalnicah omejen zgolj na pakirano hrano. <b>OBVEZNA<\/b> <b>OPREMA<\/b> vsakega tekmovalca je lasten kozar\u010dek\/bidon za to\u010denje pija\u010de.<\/p>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\"><b>ORGANIZACIJA<\/b> <b>OKREP\u010cEVALNIC<\/b> bo urejena <b>BREZKONTAKTNO<\/b>, po priporo\u010dilih organizacije <b>ITRA<\/b>. Tekmovalci ne bodo imeli neposrednega stika s ponudbo na okrep\u010devalnici, vsak bo izbrano hrano in pija\u010do dobil individualno postre\u017eeno s strani prostovoljca. Na vsaki okrep\u010devalnici bodo na voljo: voda, isotonik, coca-cola, energijske plo\u0161\u010dice in geli, slani prigrizki, banane ter kruh in sladki namazi.<\/p>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Okrep\u010devalnice bodo opremljene s hrano in pija\u010do prilagojeno dol\u017eini trase<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna.<\/p>","protected":false},"author":1,"featured_media":645,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"two_page_speed":[],"footnotes":""},"categories":[6],"tags":[],"class_list":["post-644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novice"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"agantar\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Hg Trail Idrija - Traili v Idriji\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Organizacija okrep\u010devalnic - Hg Trail Idrija\" \/>\n\t\t<meta property=\"og:description\" content=\"Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2022\/03\/hutidrija_logo-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2022\/03\/hutidrija_logo-1.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"406\" \/>\n\t\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-08-14T10:58:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-08-17T10:07:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HgTRAILIdrija\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Organizacija okrep\u010devalnic - Hg Trail Idrija\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2022\/03\/hutidrija_logo-1.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#blogposting\",\"name\":\"Organizacija okrep\\u010devalnic - Hg Trail Idrija\",\"headline\":\"Organizacija okrep\\u010devalnic\",\"author\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/author\\\/agantar\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/hgtrail-idrija.si\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/1200x628-OKREPNE.jpg\",\"width\":2500,\"height\":1308},\"datePublished\":\"2020-08-14T10:58:26+00:00\",\"dateModified\":\"2020-08-17T10:07:44+00:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#webpage\"},\"articleSection\":\"novice\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/category\\\/novice\\\/#listItem\",\"name\":\"novice\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/category\\\/novice\\\/#listItem\",\"position\":2,\"name\":\"novice\",\"item\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/category\\\/novice\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#listItem\",\"name\":\"Organizacija okrep\\u010devalnic\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#listItem\",\"position\":3,\"name\":\"Organizacija okrep\\u010devalnic\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/category\\\/novice\\\/#listItem\",\"name\":\"novice\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/#organization\",\"name\":\"Hg Trail Idrija\",\"description\":\"Traili v Idriji\",\"url\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/\",\"telephone\":\"+38651440557\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/hgtrail-idrija.si\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/hutidrija_logo-1.png\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#organizationLogo\",\"width\":406,\"height\":368},\"image\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HgTRAILIdrija\",\"https:\\\/\\\/www.instagram.com\\\/hgtrailidrija\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/author\\\/agantar\\\/#author\",\"url\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/author\\\/agantar\\\/\",\"name\":\"agantar\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b96690762ef8385c489ad18a9a71809fb2e0b4b230d35f54255872c6eb4b536?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"agantar\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#webpage\",\"url\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/\",\"name\":\"Organizacija okrep\\u010devalnic - Hg Trail Idrija\",\"description\":\"Poudariti moramo, da je leto\\u0161nja tekma v veliki meri samooskrbna.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/author\\\/agantar\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/author\\\/agantar\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/hgtrail-idrija.si\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/1200x628-OKREPNE.jpg\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#mainImage\",\"width\":2500,\"height\":1308},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/2020\\\/08\\\/14\\\/organizacija-okrepcevalnic\\\/#mainImage\"},\"datePublished\":\"2020-08-14T10:58:26+00:00\",\"dateModified\":\"2020-08-17T10:07:44+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/\",\"name\":\"Hg Trail Idrija\",\"description\":\"Traili v Idriji\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/hgtrail-idrija.si\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Organizacija okrep\u010devalnic - Hg Trail Idrija","description":"Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna.","canonical_url":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#blogposting","name":"Organizacija okrep\u010devalnic - Hg Trail Idrija","headline":"Organizacija okrep\u010devalnic","author":{"@id":"https:\/\/hgtrail-idrija.si\/en\/author\/agantar\/#author"},"publisher":{"@id":"https:\/\/hgtrail-idrija.si\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2020\/08\/1200x628-OKREPNE.jpg","width":2500,"height":1308},"datePublished":"2020-08-14T10:58:26+00:00","dateModified":"2020-08-17T10:07:44+00:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#webpage"},"isPartOf":{"@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#webpage"},"articleSection":"novice"},{"@type":"BreadcrumbList","@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/hgtrail-idrija.si\/en#listItem","position":1,"name":"Home","item":"https:\/\/hgtrail-idrija.si\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/hgtrail-idrija.si\/en\/category\/novice\/#listItem","name":"novice"}},{"@type":"ListItem","@id":"https:\/\/hgtrail-idrija.si\/en\/category\/novice\/#listItem","position":2,"name":"novice","item":"https:\/\/hgtrail-idrija.si\/en\/category\/novice\/","nextItem":{"@type":"ListItem","@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#listItem","name":"Organizacija okrep\u010devalnic"},"previousItem":{"@type":"ListItem","@id":"https:\/\/hgtrail-idrija.si\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#listItem","position":3,"name":"Organizacija okrep\u010devalnic","previousItem":{"@type":"ListItem","@id":"https:\/\/hgtrail-idrija.si\/en\/category\/novice\/#listItem","name":"novice"}}]},{"@type":"Organization","@id":"https:\/\/hgtrail-idrija.si\/en\/#organization","name":"Hg Trail Idrija","description":"Traili v Idriji","url":"https:\/\/hgtrail-idrija.si\/en\/","telephone":"+38651440557","logo":{"@type":"ImageObject","url":"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2022\/03\/hutidrija_logo-1.png","@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#organizationLogo","width":406,"height":368},"image":{"@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/HgTRAILIdrija","https:\/\/www.instagram.com\/hgtrailidrija"]},{"@type":"Person","@id":"https:\/\/hgtrail-idrija.si\/en\/author\/agantar\/#author","url":"https:\/\/hgtrail-idrija.si\/en\/author\/agantar\/","name":"agantar","image":{"@type":"ImageObject","@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3b96690762ef8385c489ad18a9a71809fb2e0b4b230d35f54255872c6eb4b536?s=96&d=mm&r=g","width":96,"height":96,"caption":"agantar"}},{"@type":"WebPage","@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#webpage","url":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/","name":"Organizacija okrep\u010devalnic - Hg Trail Idrija","description":"Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/hgtrail-idrija.si\/en\/#website"},"breadcrumb":{"@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#breadcrumblist"},"author":{"@id":"https:\/\/hgtrail-idrija.si\/en\/author\/agantar\/#author"},"creator":{"@id":"https:\/\/hgtrail-idrija.si\/en\/author\/agantar\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2020\/08\/1200x628-OKREPNE.jpg","@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#mainImage","width":2500,"height":1308},"primaryImageOfPage":{"@id":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/#mainImage"},"datePublished":"2020-08-14T10:58:26+00:00","dateModified":"2020-08-17T10:07:44+00:00"},{"@type":"WebSite","@id":"https:\/\/hgtrail-idrija.si\/en\/#website","url":"https:\/\/hgtrail-idrija.si\/en\/","name":"Hg Trail Idrija","description":"Traili v Idriji","inLanguage":"en-GB","publisher":{"@id":"https:\/\/hgtrail-idrija.si\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Hg Trail Idrija - Traili v Idriji","og:type":"article","og:title":"Organizacija okrep\u010devalnic - Hg Trail Idrija","og:description":"Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna.","og:url":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/","og:image":"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2022\/03\/hutidrija_logo-1.png","og:image:secure_url":"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2022\/03\/hutidrija_logo-1.png","og:image:width":406,"og:image:height":368,"article:published_time":"2020-08-14T10:58:26+00:00","article:modified_time":"2020-08-17T10:07:44+00:00","article:publisher":"https:\/\/www.facebook.com\/HgTRAILIdrija","twitter:card":"summary_large_image","twitter:title":"Organizacija okrep\u010devalnic - Hg Trail Idrija","twitter:description":"Poudariti moramo, da je leto\u0161nja tekma v veliki meri samooskrbna.","twitter:image":"https:\/\/hgtrail-idrija.si\/wp-content\/uploads\/2022\/03\/hutidrija_logo-1.png"},"aioseo_meta_data":{"post_id":"644","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-08-01 10:22:11","updated":"2025-06-04 08:53:26","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/hgtrail-idrija.si\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/hgtrail-idrija.si\/en\/category\/novice\/\" title=\"novice\">novice<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOrganizacija okrep\u010devalnic\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/hgtrail-idrija.si\/en"},{"label":"novice","link":"https:\/\/hgtrail-idrija.si\/en\/category\/novice\/"},{"label":"Organizacija okrep\u010devalnic","link":"https:\/\/hgtrail-idrija.si\/en\/2020\/08\/14\/organizacija-okrepcevalnic\/"}],"_links":{"self":[{"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/posts\/644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/comments?post=644"}],"version-history":[{"count":3,"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/posts\/644\/revisions"}],"predecessor-version":[{"id":654,"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/posts\/644\/revisions\/654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/media\/645"}],"wp:attachment":[{"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/media?parent=644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/categories?post=644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hgtrail-idrija.si\/en\/wp-json\/wp\/v2\/tags?post=644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}